{"id":57860,"date":"2024-09-10T05:23:46","date_gmt":"2024-09-10T08:23:46","guid":{"rendered":"https:\/\/jornadasebprioicprj.com.br\/2024\/?p=57860"},"modified":"2024-09-10T07:39:29","modified_gmt":"2024-09-10T10:39:29","slug":"bibliografia-comentada-gloria-maron","status":"publish","type":"post","link":"https:\/\/jornadasebprioicprj.com.br\/2024\/bibliografia-comentada-gloria-maron\/","title":{"rendered":"Bibliografia Comentada: Gl\u00f3ria Maron"},"content":{"rendered":"<h5><em>Gl\u00f3ria Maron <\/em><\/h5>\n<p style=\"padding-left: 120px;\"><em>\u00a0<\/em>\u201cDigamos que, no investimento de capital da empresa comum, o paciente n\u00e3o \u00e9 o \u00fanico com dificuldades a entrar com sua quota. Tamb\u00e9m o analista tem que pagar: \u2013 pagar com suas palavras, sem d\u00favida, se a transmuta\u00e7\u00e3o que elas sofrem pela opera\u00e7\u00e3o anal\u00edtica as eleva a seu efeito de interpreta\u00e7\u00e3o.\u201d<\/p>\n<p>LACAN, J. A dire\u00e7\u00e3o do tratamento e os princ\u00edpios do seu poder (1958). <em>Escritos<\/em>. Rio de Janeiro: Zahar, 1998, p. 593.<\/p>\n<p>Palavra e linguagem s\u00e3o dois termos-chave do ensino inaugural de Lacan e est\u00e3o presentes no escrito \u201cA dire\u00e7\u00e3o do tratamento e os princ\u00edpios do seu poder\u201d. Esse texto, conserva a sua import\u00e2ncia e atualidade para a orienta\u00e7\u00e3o da pr\u00e1tica do analista, quando Lacan retorna a Freud para abordar o fundamento da palavra na experi\u00eancia anal\u00edtica. Lacan amplifica o que costumamos no dia a dia sustentar: a experi\u00eancia anal\u00edtica opera pela palavra. Longe de ser uma rela\u00e7\u00e3o dual, a palavra \u00e9 um elemento importante na <em>situa\u00e7\u00e3o anal\u00edtica<\/em>, dominada \u00e0 \u00e9poca desse escrito, pela vertente imagin\u00e1ria na pr\u00e1tica anal\u00edtica dos p\u00f3s-freudianos<em>.<\/em> Nesse texto, no que tange \u00e0 interpreta\u00e7\u00e3o enquanto t\u00e1tica, Lacan sustenta que o analista se apresenta mais livre quanto ao momento, ao n\u00famero e \u00e0 escolha de suas interven\u00e7\u00f5es. Todavia, para que a palavra do analista possa adquirir efeito de interpreta\u00e7\u00e3o, adverte Lacan, a transmuta\u00e7\u00e3o da palavra n\u00e3o \u00e9 dada pela pessoa do analista, mas \u00e9 atravessada necessariamente pelo lugar que a transfer\u00eancia confere ao analista.<a href=\"#_ftn1\" name=\"_ftnref1\"><sup>[1]<\/sup><\/a> Sua advert\u00eancia avan\u00e7a na dire\u00e7\u00e3o de distinguir uma interven\u00e7\u00e3o \u201cesclarecedora\u201d, carregada de sentido e que se coloca a servi\u00e7o de tamponar e contribuir para o fechamento do inconsciente, de uma interpreta\u00e7\u00e3o e seu efeito de abertura<a href=\"#_ftn2\" name=\"_ftnref2\"><sup>[2]<\/sup><\/a>, que preserva que h\u00e1 um indiz\u00edvel na experi\u00eancia anal\u00edtica.<\/p>\n<p>N\u00e3o h\u00e1 regras para a interpreta\u00e7\u00e3o, mas como aponta o escrito, h\u00e1 princ\u00edpios que orientam a pr\u00e1tica do psicanalista. Podemos deixar em aberto uma afirma\u00e7\u00e3o sutil e ir\u00f4nica de Lacan, que, de certo modo, comporta um enigma: \u201cUma interpreta\u00e7\u00e3o s\u00f3 pode ser exata se for&#8230; uma interpreta\u00e7\u00e3o\u201d.<a href=\"#_ftn3\" name=\"_ftnref3\"><sup>[3]<\/sup><\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h5><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Lacan, J. A dire\u00e7\u00e3o do tratamento e os princ\u00edpios do seu poder. <em>Escritos<\/em>. Zahar: Rio de Janeiro, 1998, p. 597.<\/h5>\n<h5><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Lacan, J. A dire\u00e7\u00e3o do tratamento e os princ\u00edpios do seu poder, p. 599.<\/h5>\n<h5><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> Lacan, J. A dire\u00e7\u00e3o do tratamento e os princ\u00edpios do seu poder, p. 607.<\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Gl\u00f3ria Maron \u00a0\u201cDigamos que, no investimento de capital da empresa comum, o paciente n\u00e3o \u00e9 o \u00fanico com dificuldades a entrar com sua quota. Tamb\u00e9m o analista tem que pagar: \u2013 pagar com suas palavras, sem d\u00favida, se a transmuta\u00e7\u00e3o que elas sofrem pela opera\u00e7\u00e3o anal\u00edtica as eleva a seu efeito de interpreta\u00e7\u00e3o.\u201d LACAN, J.&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[521],"tags":[],"class_list":["post-57860","post","type-post","status-publish","format-standard","hentry","category-referencias-comentadas","category-521","description-off"],"_links":{"self":[{"href":"https:\/\/jornadasebprioicprj.com.br\/2024\/wp-json\/wp\/v2\/posts\/57860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornadasebprioicprj.com.br\/2024\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornadasebprioicprj.com.br\/2024\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornadasebprioicprj.com.br\/2024\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornadasebprioicprj.com.br\/2024\/wp-json\/wp\/v2\/comments?post=57860"}],"version-history":[{"count":3,"href":"https:\/\/jornadasebprioicprj.com.br\/2024\/wp-json\/wp\/v2\/posts\/57860\/revisions"}],"predecessor-version":[{"id":57863,"href":"https:\/\/jornadasebprioicprj.com.br\/2024\/wp-json\/wp\/v2\/posts\/57860\/revisions\/57863"}],"wp:attachment":[{"href":"https:\/\/jornadasebprioicprj.com.br\/2024\/wp-json\/wp\/v2\/media?parent=57860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornadasebprioicprj.com.br\/2024\/wp-json\/wp\/v2\/categories?post=57860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornadasebprioicprj.com.br\/2024\/wp-json\/wp\/v2\/tags?post=57860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}