{"id":770,"date":"2021-11-04T07:20:29","date_gmt":"2021-11-04T10:20:29","guid":{"rendered":"https:\/\/jornadasebprioicprj.com.br\/2021\/?p=770"},"modified":"2021-11-04T07:20:29","modified_gmt":"2021-11-04T10:20:29","slug":"iia-mesa-preparatoria-o-nome-do-medo","status":"publish","type":"post","link":"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/","title":{"rendered":"II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo"},"content":{"rendered":"<h6><strong>Artista convidada<\/strong>: Rivane Neuenschwander<\/h6>\n<h6><strong>Cartel:<\/strong> F\u00e1tima Pinheiro, Flavia Corpas, Giselle Falbo, Paula Legey, Sarita Gelbert (mais um) e Thereza De Felice<\/h6>\n<p><strong>\u00a0<\/strong><strong>Texto introdut\u00f3rio da preparat\u00f3ria <\/strong><\/p>\n<h6><em>Por F\u00e1tima Pinheiro <\/em><\/h6>\n<p>Por que situar a arte neste momento preparat\u00f3rio \u00e0s nossas Jornadas?<\/p>\n<p>Podemos recorrer ao que j\u00e1 se sabe: dizer que arte \u00e9 um instrumento de resist\u00eancia. E, \u00e9 mesmo, especialmente nesse tempo das necropol\u00edticas vigentes. Ela \u00e9 fundamental, tamb\u00e9m, por reavivar a rela\u00e7\u00e3o existente entre nome e vida, uma vez que introduz uma po\u00e9tica, que \u00e9 um modo de resistir \u00e0 prosa do mundo contempor\u00e2neo, sustentada pelo imp\u00e9rio massificante da \u201cutilidade direta\u201d<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. A arte opera bagun\u00e7ando nossos h\u00e1bitos, e circunscreve o mal-estar, ali onde ele aparece no la\u00e7o com o outro. Introduz, assim, al\u00e9m da po\u00e9tica, a pol\u00edtica, no aspecto mais caro a n\u00f3s psicanalistas: a pol\u00edtica do sintoma.<\/p>\n<p>Convidamos, a artista Rivane Neuenschwander, para conversar conosco, a partir de seu trabalho \u201cO Nome do medo\u201d, a quem agrade\u00e7o a presen\u00e7a em nome da diretoria da EBP Rio e do ICP &#8211; RJ, das Comiss\u00f5es das Jornadas deste ano, e do cartel, a qual fa\u00e7o parte, que coordenar\u00e1 nosso encontro hoje. Agrade\u00e7o, tamb\u00e9m, \u00e0 Tania Rivera, que possibilitou o nosso contato com Rivane.<\/p>\n<p>Rivane, nasceu em Belo Horizonte, e vive em S\u00e3o Paulo. \u00c9 hoje, uma das artistas visuais brasileiras de maior reconhecimento internacional.\u00a0 Participou de in\u00fameras exposi\u00e7\u00f5es coletivas nacionais e internacionais, como as Bienais de Veneza (de 2003 e de 2005), e as Bienais de S\u00e3o Paulo, em 2006 e 2008. Transita entre pintura, escultura, instala\u00e7\u00e3o, v\u00eddeo, e a\u00e7\u00f5es participat\u00f3rias.\u00a0 Suas obras est\u00e3o em grandes cole\u00e7\u00f5es institucionais como Tate Modern (Londres), Guggenheim (Nova York), Moma (Nova York), TBA 21 (Viena), e Inhotim (Brumadinho).<\/p>\n<hr \/>\n<h6><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> Miller. J. A. Un esfuerzo de poes\u00eda:\u00a0Buenos Aires: Paid\u00f3s, 2016, p. 159.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Artista convidada: Rivane Neuenschwander Cartel: F\u00e1tima Pinheiro, Flavia Corpas, Giselle Falbo, Paula Legey, Sarita Gelbert (mais um) e Thereza De Felice \u00a0Texto introdut\u00f3rio da preparat\u00f3ria Por F\u00e1tima Pinheiro Por que situar a arte neste momento preparat\u00f3rio \u00e0s nossas Jornadas? Podemos recorrer ao que j\u00e1 se sabe: dizer que arte \u00e9 um instrumento de resist\u00eancia. E, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-770","post","type-post","status-publish","format-standard","hentry","category-boletim-gps"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo - Jornadas EBP RIO e ICPRJ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo - Jornadas EBP RIO e ICPRJ\" \/>\n<meta property=\"og:description\" content=\"Artista convidada: Rivane Neuenschwander Cartel: F\u00e1tima Pinheiro, Flavia Corpas, Giselle Falbo, Paula Legey, Sarita Gelbert (mais um) e Thereza De Felice \u00a0Texto introdut\u00f3rio da preparat\u00f3ria Por F\u00e1tima Pinheiro Por que situar a arte neste momento preparat\u00f3rio \u00e0s nossas Jornadas? Podemos recorrer ao que j\u00e1 se sabe: dizer que arte \u00e9 um instrumento de resist\u00eancia. E, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornadas EBP RIO e ICPRJ\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-04T10:20:29+00:00\" \/>\n<meta name=\"author\" content=\"jornadas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jornadas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/iia-mesa-preparatoria-o-nome-do-medo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/iia-mesa-preparatoria-o-nome-do-medo\\\/\"},\"author\":{\"name\":\"jornadas\",\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/#\\\/schema\\\/person\\\/a877eeb013edee082dbca99cad8bfc67\"},\"headline\":\"II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo\",\"datePublished\":\"2021-11-04T10:20:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/iia-mesa-preparatoria-o-nome-do-medo\\\/\"},\"wordCount\":327,\"articleSection\":[\"Boletim GPS\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/iia-mesa-preparatoria-o-nome-do-medo\\\/\",\"url\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/iia-mesa-preparatoria-o-nome-do-medo\\\/\",\"name\":\"II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo - Jornadas EBP RIO e ICPRJ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/#website\"},\"datePublished\":\"2021-11-04T10:20:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/#\\\/schema\\\/person\\\/a877eeb013edee082dbca99cad8bfc67\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/iia-mesa-preparatoria-o-nome-do-medo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/iia-mesa-preparatoria-o-nome-do-medo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/iia-mesa-preparatoria-o-nome-do-medo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/#website\",\"url\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/\",\"name\":\"Jornadas EBP RIO e ICPRJ\",\"description\":\"Escola Brasileira de Psican\u00e1lise\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/#\\\/schema\\\/person\\\/a877eeb013edee082dbca99cad8bfc67\",\"name\":\"jornadas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d60d0f34e016dd50f9c3df6f5f4269aafa63cefe878ea546810736b04c310191?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d60d0f34e016dd50f9c3df6f5f4269aafa63cefe878ea546810736b04c310191?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d60d0f34e016dd50f9c3df6f5f4269aafa63cefe878ea546810736b04c310191?s=96&d=mm&r=g\",\"caption\":\"jornadas\"},\"sameAs\":[\"http:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\"],\"url\":\"https:\\\/\\\/jornadasebprioicprj.com.br\\\/2021\\\/author\\\/jornadas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo - Jornadas EBP RIO e ICPRJ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/","og_locale":"pt_BR","og_type":"article","og_title":"II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo - Jornadas EBP RIO e ICPRJ","og_description":"Artista convidada: Rivane Neuenschwander Cartel: F\u00e1tima Pinheiro, Flavia Corpas, Giselle Falbo, Paula Legey, Sarita Gelbert (mais um) e Thereza De Felice \u00a0Texto introdut\u00f3rio da preparat\u00f3ria Por F\u00e1tima Pinheiro Por que situar a arte neste momento preparat\u00f3rio \u00e0s nossas Jornadas? Podemos recorrer ao que j\u00e1 se sabe: dizer que arte \u00e9 um instrumento de resist\u00eancia. E, [&hellip;]","og_url":"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/","og_site_name":"Jornadas EBP RIO e ICPRJ","article_published_time":"2021-11-04T10:20:29+00:00","author":"jornadas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jornadas","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/#article","isPartOf":{"@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/"},"author":{"name":"jornadas","@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/#\/schema\/person\/a877eeb013edee082dbca99cad8bfc67"},"headline":"II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo","datePublished":"2021-11-04T10:20:29+00:00","mainEntityOfPage":{"@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/"},"wordCount":327,"articleSection":["Boletim GPS"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/","url":"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/","name":"II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo - Jornadas EBP RIO e ICPRJ","isPartOf":{"@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/#website"},"datePublished":"2021-11-04T10:20:29+00:00","author":{"@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/#\/schema\/person\/a877eeb013edee082dbca99cad8bfc67"},"breadcrumb":{"@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/iia-mesa-preparatoria-o-nome-do-medo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornadasebprioicprj.com.br\/2021\/"},{"@type":"ListItem","position":2,"name":"II\u00aa Mesa Preparat\u00f3ria: O Nome do Medo"}]},{"@type":"WebSite","@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/#website","url":"https:\/\/jornadasebprioicprj.com.br\/2021\/","name":"Jornadas EBP RIO e ICPRJ","description":"Escola Brasileira de Psican\u00e1lise","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornadasebprioicprj.com.br\/2021\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/jornadasebprioicprj.com.br\/2021\/#\/schema\/person\/a877eeb013edee082dbca99cad8bfc67","name":"jornadas","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d60d0f34e016dd50f9c3df6f5f4269aafa63cefe878ea546810736b04c310191?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d60d0f34e016dd50f9c3df6f5f4269aafa63cefe878ea546810736b04c310191?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d60d0f34e016dd50f9c3df6f5f4269aafa63cefe878ea546810736b04c310191?s=96&d=mm&r=g","caption":"jornadas"},"sameAs":["http:\/\/jornadasebprioicprj.com.br\/2021"],"url":"https:\/\/jornadasebprioicprj.com.br\/2021\/author\/jornadas\/"}]}},"_links":{"self":[{"href":"https:\/\/jornadasebprioicprj.com.br\/2021\/wp-json\/wp\/v2\/posts\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornadasebprioicprj.com.br\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornadasebprioicprj.com.br\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornadasebprioicprj.com.br\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornadasebprioicprj.com.br\/2021\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":1,"href":"https:\/\/jornadasebprioicprj.com.br\/2021\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"predecessor-version":[{"id":771,"href":"https:\/\/jornadasebprioicprj.com.br\/2021\/wp-json\/wp\/v2\/posts\/770\/revisions\/771"}],"wp:attachment":[{"href":"https:\/\/jornadasebprioicprj.com.br\/2021\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornadasebprioicprj.com.br\/2021\/wp-json\/wp\/v2\/categories?post=770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornadasebprioicprj.com.br\/2021\/wp-json\/wp\/v2\/tags?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}